{"id":10152,"date":"2023-11-15T15:27:01","date_gmt":"2023-11-15T11:57:01","guid":{"rendered":"https:\/\/www.vent.ir\/fa\/?p=10152"},"modified":"2023-11-15T15:27:01","modified_gmt":"2023-11-15T11:57:01","slug":"%d8%aa%d9%87%d9%88%db%8c%d9%87-%d9%be%d8%a7%d8%b1%da%a9%db%8c%d9%86%da%af-%d9%87%d8%a7%db%8c-%d8%b2%db%8c%d8%b1-%d8%b2%d9%85%db%8c%d9%86%db%8c","status":"publish","type":"post","link":"https:\/\/www.vent.ir\/fa\/%d8%aa%d9%87%d9%88%db%8c%d9%87-%d9%be%d8%a7%d8%b1%da%a9%db%8c%d9%86%da%af-%d9%87%d8%a7%db%8c-%d8%b2%db%8c%d8%b1-%d8%b2%d9%85%db%8c%d9%86%db%8c\/","title":{"rendered":"\u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0628\u0647 \u0686\u0647 \u0635\u0648\u0631\u062a \u0627\u0633\u062a \u061f"},"content":{"rendered":"<p>\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u0645 \u0628\u0647 \u0646\u0642\u062f \u0648 \u0628\u0631\u0631\u0633\u06cc \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0628\u067e\u0631\u062f\u0627\u0632\u06cc\u0645. \u0628\u0627\u06cc\u062f \u0627\u0630\u0639\u0627\u0646 \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0628\u062e\u0634 \u0627\u0635\u0644\u06cc \u0648 \u0627\u0633\u0627\u0633\u06cc \u062f\u0631 \u0647\u0645\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627 \u0648 \u0628\u0647 \u062e\u0635\u0648\u0635 \u062f\u0631 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc \u0631\u0648\u0646\u062f. \u062f\u0631 \u0627\u0628\u062a\u062f\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062f\u0631 \u0645\u0648\u0631\u062f \u0636\u0631\u0648\u0631\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc\u060c \u0645\u0637\u0627\u0644\u0628\u06cc \u0631\u0627 \u0628\u06cc\u0627\u0646 \u0645\u06cc \u06a9\u0646\u06cc\u0645. \u067e\u0633 \u0627\u0632 \u0622\u0646 \u0648\u0638\u06cc\u0641\u0647 \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0631\u0627 \u0630\u06a9\u0631 \u0645\u06cc \u06a9\u0646\u06cc\u0645. \u0628\u0639\u062f \u0627\u0632 \u0622\u0646 \u0646\u06cc\u0632 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u200c\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0627\u0632 \u0686\u0647 \u0627\u062c\u0632\u0627\u06cc\u06cc \u062a\u0634\u06a9\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0646\u062f. \u062f\u0631 \u0627\u0646\u062a\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0646\u06cc\u0632 \u0645\u0632\u0627\u06cc\u0627\u06cc \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0631\u0627 \u0628\u06cc\u0627\u0646 \u0645\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n<p>&nbsp;<\/p>\n<h2>\u0644\u0632\u0648\u0645 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc<\/h2>\n<p>\u0627\u0645\u0631\u0648\u0632\u0647 \u062a\u0639\u062f\u0627\u062f \u062e\u0648\u062f\u0631\u0648\u0647\u0627 \u0628\u0647 \u0647\u06cc\u0686 \u0639\u0646\u0648\u0627\u0646 \u0628\u0627 \u0633\u0627\u0644 \u0647\u0627\u06cc \u062f\u0648\u0631 \u0642\u0627\u0628\u0644 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0646\u06cc\u0633\u062a. \u0632\u06cc\u0627\u062f \u0634\u062f\u0646 \u062a\u0639\u062f\u0627\u062f \u062e\u0648\u062f\u0631\u0648\u0647\u0627 \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0628\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0646\u06cc\u0627\u0632 \u0628\u0627\u0634\u062f. \u0627\u0645\u0631\u0648\u0632\u0647 \u062e\u0631\u06cc\u062f\u0646 \u06cc\u06a9 \u0648\u0627\u062d\u062f \u0622\u067e\u0627\u0631\u062a\u0645\u0627\u0646\u06cc \u0648 \u062d\u062a\u06cc \u0648\u0627\u062d\u062f \u062a\u062c\u0627\u0631\u06cc \u0648 \u0627\u062f\u0627\u0631\u06cc \u0628\u062f\u0648\u0646 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u06a9\u0627\u0631 \u0645\u0646\u0637\u0642\u06cc \u0648 \u062f\u0631\u0633\u062a\u06cc \u0646\u06cc\u0633\u062a. \u0627\u06af\u0631 \u0647\u0645 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0627\u062e\u062a\u0635\u0627\u0635\u06cc \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0645\u062c\u0628\u0648\u0631 \u062e\u0648\u0627\u0647\u06cc\u062f \u0634\u062f \u06a9\u0647 \u062e\u0648\u062f\u0631\u0648\u06cc \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0637\u0628\u0642\u0627\u062a\u06cc \u0648 \u0633\u0627\u06cc\u0631 \u0627\u0646\u0648\u0627\u0639 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0639\u0645\u0648\u0645\u06cc \u067e\u0627\u0631\u06a9 \u06a9\u0646\u06cc\u062f. \u062f\u0631 \u0648\u0627\u0642\u0639 \u062f\u06cc\u06af\u0631 \u062f\u0631 \u06a9\u0648\u0686\u0647 \u0647\u0627 \u0648 \u062e\u06cc\u0627\u0628\u0627\u0646 \u0647\u0627 \u062c\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u067e\u0627\u0631\u06a9 \u06a9\u0631\u062f\u0646 \u0645\u0627\u0634\u06cc\u0646 \u067e\u06cc\u062f\u0627 \u0646\u0645\u06cc \u06a9\u0646\u06cc\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0627\u06cc\u062f \u0642\u0628\u0648\u0644 \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0627\u0645\u0631\u0648\u0632\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627 \u0627\u0647\u0645\u06cc\u062a \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f.<\/p>\n<p>\u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u200c\u0647\u0627 \u0645\u062e\u0635\u0648\u0635\u0627 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u200c\u0647\u0627\u06cc \u0639\u0645\u0648\u0645\u06cc \u06a9\u0647 \u062f\u0631 \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u0646\u062f\u060c \u06cc\u06a9 \u0633\u0631\u06cc \u0645\u06a9\u0627\u0646 \u0633\u0631 \u0628\u0633\u062a\u0647\u200c \u0627\u06cc \u0645\u06cc \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u0627\u0631\u062a\u0628\u0627\u0637 \u0632\u06cc\u0627\u062f\u06cc \u0628\u0627 \u0641\u0636\u0627\u06cc \u0628\u06cc\u0631\u0648\u0646 \u0648 \u0647\u0648\u0627\u06cc \u0622\u0632\u0627\u062f \u0646\u062f\u0627\u0631\u0646\u062f. \u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631\u060c \u0645\u0627\u0634\u06cc\u0646 \u0647\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0641\u0636\u0627\u0647\u0627 \u062e\u06cc\u0644\u06cc \u0631\u0641\u062a \u0648 \u0622\u0645\u062f \u0645\u06cc \u06a9\u0646\u0646\u062f \u0648 \u062f\u0648\u062f \u062e\u0627\u0631\u062c \u0634\u062f\u0647 \u0627\u0632 \u0622\u0646 \u0647\u0627 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af\u200c \u0647\u0627 \u0628\u0627\u0642\u06cc \u0645\u06cc \u200c\u0645\u0627\u0646\u062f \u0648 \u0628\u0647 \u062e\u0627\u0631\u062c \u0627\u0632 \u0622\u0646 \u0646\u0645\u06cc \u0631\u0648\u062f. \u0627\u0632 \u0622\u0646 \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0634\u0647\u0631\u0647\u0627 \u0641\u0636\u0627 \u0645\u062d\u062f\u0648\u062f \u0627\u0633\u062a \u0648 \u0647\u0645\u0648\u0627\u0631\u0647 \u0628\u0647 \u062c\u0645\u0639\u06cc\u062a \u0634\u0647\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0636\u0627\u0641\u0647 \u0645\u06cc \u0634\u0648\u062f \u0648 \u0627\u0632 \u0637\u0631\u0641 \u062f\u06cc\u06af\u0631 \u0647\u062a\u0644\u200c \u0647\u0627 \u0648 \u0622\u067e\u0627\u0631\u062a\u0645\u0627\u0646 \u200c\u0647\u0627\u06cc \u0686\u0646\u062f \u0637\u0628\u0642\u0647 \u0632\u06cc\u0627\u062f \u0645\u06cc \u0634\u0648\u0646\u062f\u060c \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af\u200c \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0631\u0648\u0632 \u0628\u0647 \u0631\u0648\u0632 \u062f\u0631 \u062d\u0627\u0644 \u0632\u06cc\u0627\u062f \u0634\u062f\u0646 \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0639\u0627\u0645\u0644 \u0645\u0648\u062c\u0628 \u0645\u06cc \u06af\u0631\u062f\u062f \u06a9\u0647 \u0631\u0648\u0632 \u0628\u0647 \u0631\u0648\u0632 \u0628\u0647 \u062a\u0639\u062f\u0627\u062f\u00a0 \u0633\u06cc\u0633\u062a\u0645 \u0647\u0627\u06cc \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0627\u0641\u0632\u0648\u062f\u0647 \u0634\u0648\u062f.<\/p>\n<h2><a href=\"http:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-10153 size-full\" src=\"http:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/1.png\" alt=\"\u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af\u06cc\" width=\"700\" height=\"320\" srcset=\"https:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/1.png 700w, https:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/1-300x137.png 300w, https:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/1-200x91.png 200w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/h2>\n<h2>\u0648\u0638\u06cc\u0641\u0647 \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc<\/h2>\n<p>\u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0628\u0627\u06cc\u0633\u062a\u06cc \u062f\u0627\u0631\u0627\u06cc \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0627\u0634\u0646\u062f. \u062f\u0644\u06cc\u0644 \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0647\u0645 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0648\u062f \u0645\u0627\u0634\u06cc\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u06a9\u0627\u0646 \u0647\u0627 \u0632\u06cc\u0627\u062f \u0627\u0633\u062a. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627 \u062f\u0631 \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646 \u0628\u0627\u0634\u0646\u062f \u0646\u06cc\u0627\u0632 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a. \u0628\u0647 \u0647\u06cc\u0686 \u0639\u0646\u0648\u0627\u0646 \u0646\u0628\u0627\u06cc\u062f \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0631\u0627 \u062f\u0633\u062a \u06a9\u0645 \u0628\u06af\u06cc\u0631\u06cc\u062f. \u0633\u06cc\u0633\u062a\u0645 \u00a0\u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0622\u0644\u0627\u06cc\u0646\u062f\u0647 \u0647\u0627 \u0631\u0627 \u062a\u0627 \u062d\u062f \u0632\u06cc\u0627\u062f\u06cc \u06a9\u0645 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0633\u06cc\u0633\u062a\u0645 \u00a0\u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc\u060c\u064e \u062f\u0648\u062f \u062d\u0627\u0635\u0644 \u0627\u0632 \u06a9\u0627\u0631 \u06a9\u0631\u062f\u0646 \u0645\u0627\u0634\u06cc\u0646 \u0647\u0627\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0631\u0627 \u06a9\u0646\u062a\u0631\u0644 \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0622\u0646 \u0647\u0627 \u0631\u0627 \u062e\u0627\u0631\u062c \u0645\u06cc \u06a9\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645\u060c \u0647\u0648\u0627\u06cc \u062a\u0627\u0632\u0647 \u0631\u0627 \u0648\u0627\u0631\u062f \u0641\u0636\u0627\u06cc \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0628\u0627 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0628\u0627\u0639\u062b \u062a\u0647\u0648\u06cc\u0647 \u0647\u0648\u0627\u06cc \u0645\u062d\u06cc\u0637 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<p>\u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631 \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u0622\u062a\u0634\u200c \u0633\u0648\u0632\u06cc \u0647\u0645 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062e\u06cc\u0644\u06cc \u0645\u0641\u06cc\u062f \u0628\u0627\u0634\u0646\u062f. \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u06a9\u0646\u062a\u0631\u0644 \u0648 \u062a\u062e\u0644\u06cc\u0647 \u062f\u0648\u062f \u0648 \u0627\u0644\u0628\u062a\u0647 \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u062f\u0633\u062a\u0631\u0633\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0622\u062a\u0634 \u0646\u0634\u0627\u0646\u0627\u0646 \u062e\u06cc\u0644\u06cc \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a. \u0628\u0647 \u0639\u0644\u0627\u0648\u0647\u060c \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc\u060c \u062f\u0631 \u0645\u0648\u0642\u0639 \u0622\u062a\u0634 \u0633\u0648\u0632\u06cc \u0628\u0647 \u0627\u0641\u0631\u0627\u062f \u0641\u0631\u0635\u062a \u06a9\u0627\u0641\u06cc \u0631\u0627 \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u062f \u06a9\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0631\u0627 \u062a\u062e\u0644\u06cc\u0647 \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0645\u062c\u0645\u0648\u0639\u0647 \u0627\u06cc \u0627\u0632 \u0633\u06cc\u0633\u062a\u0645 \u0647\u0627 \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0627\u0633\u062a \u06a9\u0647 \u0634\u0631\u0627\u06cc\u0637 \u0631\u0627\u062d\u062a \u0648 \u0627\u06cc\u0645\u0646\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062e\u0648\u062f\u0631\u0648\u0647\u0627 \u0648 \u0627\u0641\u0631\u0627\u062f \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0634\u0627\u0645\u0644 \u0648\u0631\u0648\u062f\u06cc \u0648 \u062e\u0631\u0648\u062c\u06cc \u0647\u0648\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u06af\u0631\u0645\u0627\u06cc\u0634\u06cc \u0648 \u0633\u0631\u0645\u0627\u06cc\u0634\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627\u0639\u062b \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0631\u062f\u0646 \u062f\u0645\u0627 \u0648 \u062a\u0647\u0648\u06cc\u0647 \u0641\u0636\u0627\u06cc \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<p>&nbsp;<\/p>\n<h2>\u0627\u062c\u0632\u0627\u06cc \u062a\u0634\u06a9\u06cc\u0644 \u062f\u0647\u0646\u062f\u0647 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u200c\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc<\/h2>\n<p>\u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u200c\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u06a9\u0627\u0646\u06cc\u06a9\u06cc \u0628\u0627\u0634\u0646\u062f \u0648 \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u062a\u0634\u06a9\u06cc\u0644 \u0634\u062f\u0647 \u0628\u0627\u0634\u0646\u062f:<\/p>\n<ol>\n<li>\u0641\u0646 \u200c\u0647\u0627\u06cc \u062a\u062e\u0644\u06cc\u0647 \u06a9\u0647 \u062f\u0631 \u0632\u0628\u0627\u0646 \u0627\u0646\u06af\u0644\u06cc\u0633\u06cc \u0628\u0647 Extract Fan \u0645\u0639\u0631\u0648\u0641 \u0647\u0633\u062a\u0646\u062f.<\/li>\n<li>\u062c\u062a \u0641\u0646 \u200c\u0647\u0627 \u0648 \u06cc\u0627 \u0647\u0645\u0627\u0646 Jet Fan<\/li>\n<li>\u0641\u0646\u200c\u0647\u0627\u06cc \u0647\u0648\u0627\u06cc \u062a\u0627\u0632\u0647 \u0648 \u06cc\u0627 \u0647\u0645\u0627\u0646 Supply Fan<\/li>\n<\/ol>\n<p>\u0627\u06cc\u0646 \u0645\u0648\u0627\u0631\u062f \u0628\u0627\u06cc\u0633\u062a\u06cc \u0628\u0647 \u0635\u0648\u0631\u062a \u06cc\u06a9 \u0633\u06cc\u0633\u062a\u0645 \u0628\u0627\u0634\u0646\u062f \u0648 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0647\u0645 \u06a9\u0627\u0631 \u06a9\u0646\u0646\u062f.<\/p>\n<h2><a href=\"http:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/2.jpg\"><img decoding=\"async\" class=\"alignnone wp-image-10154 size-full\" src=\"http:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/2.jpg\" alt=\"\u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af\u06cc\" width=\"1300\" height=\"650\" srcset=\"https:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/2.jpg 1300w, https:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/2-300x150.jpg 300w, https:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/2-1024x512.jpg 1024w, https:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/2-768x384.jpg 768w, https:\/\/www.vent.ir\/fa\/wp-content\/uploads\/2023\/11\/2-200x100.jpg 200w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/><\/a><\/h2>\n<h2>\u062a\u0639\u06cc\u06cc\u0646 \u0646\u0631\u062e \u062a\u0647\u0648\u06cc\u0647 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc<\/h2>\n<p>\u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0637\u0631\u0627\u062d\u06cc \u06cc\u06a9 \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u0627\u0635\u0648\u0644\u06cc \u0628\u0631\u0627\u06cc \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af\u200c \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0648 \u0633\u0631 \u0628\u0633\u062a\u0647\u060c \u0642\u0628\u0644 \u0627\u0632 \u0647\u0631 \u06a9\u0627\u0631\u06cc \u0628\u0627\u06cc\u0633\u062a\u06cc \u0646\u0631\u062e \u062a\u0647\u0648\u06cc\u0647 \u0645\u0646\u0627\u0633\u0628 \u0645\u0634\u062e\u0635 \u06af\u0631\u062f\u062f. \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u062a\u0639\u06cc\u06cc\u0646 \u0646\u0631\u062e \u062a\u0647\u0648\u06cc\u0647 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af\u200c \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc\u060c \u0628\u0627\u06cc\u062f \u062f\u0648 \u0639\u0627\u0645\u0644 \u0632\u06cc\u0631 \u0631\u0627 \u0645\u062f \u0646\u0638\u0631 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f:<\/p>\n<ol>\n<li>\u062a\u0639\u062f\u0627\u062f \u0645\u0627\u0634\u06cc\u0646 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0648\u062c\u0648\u062f \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a.<\/li>\n<li>\u0645\u06cc\u0632\u0627\u0646 \u0630\u0631\u0627\u062a\u06cc \u06a9\u0647 \u0627\u0632 \u0647\u0631 \u0645\u0627\u0634\u06cc\u0646 \u062f\u0631 \u0647\u0648\u0627 \u0645\u0646\u062a\u0634\u0631 \u0645\u06cc \u0634\u0648\u062f.<\/li>\n<\/ol>\n<p>\u0627\u0644\u0628\u062a\u0647 \u062c\u0627\u06cc \u062a\u0623\u0633\u0641 \u0627\u0633\u062a \u06a9\u0647 \u0628\u06af\u0648\u06cc\u06cc\u0645 \u062f\u0631 \u06a9\u0634\u0648\u0631 \u0645\u0627\u060c \u0646\u0631\u062e \u062a\u0647\u0648\u06cc\u0647 \u0648\u0627\u0642\u0639\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f\u0647 \u062f\u0631 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af\u200c \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0648 \u0633\u0631 \u0628\u0633\u062a\u0647 \u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u06a9\u0645 \u062a\u0631 \u0627\u0632 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0633\u062a.<\/p>\n<p>&nbsp;<\/p>\n<h2>\u0645\u0632\u0627\u06cc\u0627\u06cc \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc<\/h2>\n<p>\u062f\u0631 \u06a9\u0644\u060c \u062a\u0647\u0648\u06cc\u0647 \u0628\u0631\u0627\u06cc \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u06cc\u06a9 \u0627\u0645\u0631 \u062d\u06cc\u0627\u062a\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u06a9\u06cc\u0641\u06cc\u062a \u0632\u0646\u062f\u06af\u06cc \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0641\u0636\u0627\u0647\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u0645\u0632\u0627\u06cc\u0627\u06cc \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0634\u0627\u0645\u0644 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0627\u0633\u062a:<\/p>\n<ol>\n<li>\u062d\u0641\u0638 \u06a9\u06cc\u0641\u06cc\u062a \u0647\u0648\u0627: \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0633\u06cc\u0633\u062a\u0645 \u0647\u0627\u06cc \u062a\u0647\u0648\u06cc\u0647\u060c \u0645\u06cc \u062a\u0648\u0627\u0646 \u06a9\u06cc\u0641\u06cc\u062a \u0647\u0648\u0627\u06cc \u062f\u0627\u062e\u0644 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0631\u0627 \u062d\u0641\u0638 \u06a9\u0631\u062f \u0648 \u0627\u0632 \u0622\u0644\u0648\u062f\u0647 \u0634\u062f\u0646 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0628\u0647 \u0645\u0648\u0627\u062f\u06cc \u0645\u0627\u0646\u0646\u062f \u0645\u0648\u0627\u062f \u0622\u0644\u0627\u06cc\u0646\u062f\u0647 \u0647\u0648\u0627 \u0648 \u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0631\u062f.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li>\u06a9\u0627\u0647\u0634 \u0631\u0637\u0648\u0628\u062a: \u0633\u06cc\u0633\u062a\u0645 \u062a\u0647\u0648\u06cc\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0631\u0637\u0648\u0628\u062a \u062f\u0631 \u0641\u0636\u0627\u06cc \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062d\u0641\u0638 \u0637\u0648\u0644 \u0639\u0645\u0631 \u062e\u0648\u062f\u0631\u0648\u0647\u0627 \u0648 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0632\u0646\u06af \u0632\u062f\u06af\u06cc \u0622\u0646 \u0647\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol start=\"3\">\n<li>\u0627\u06cc\u062c\u0627\u062f \u0634\u0631\u0627\u06cc\u0637 \u0631\u0627\u062d\u062a\u06cc: \u0628\u0627 \u0627\u06cc\u062c\u0627\u062f \u062f\u0645\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0648 \u062d\u0631\u06a9\u062a \u0647\u0648\u0627\u06cc \u0645\u0646\u0627\u0633\u0628\u060c \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0628\u0647 \u0627\u06cc\u062c\u0627\u062f \u0634\u0631\u0627\u06cc\u0637 \u0631\u0627\u062d\u062a \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0648 \u0631\u0627\u0646\u0646\u062f\u06af\u0627\u0646 \u062f\u0631 \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u06a9\u0631\u062f\u0646 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u06a9\u0645\u06a9 \u0645\u06cc \u06a9\u0646\u062f.<\/li>\n<li>\u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u06cc\u0645\u0646\u06cc: \u0648\u062c\u0648\u062f \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0645\u0646\u0627\u0633\u0628 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u0645\u0627\u0646\u0646\u062f \u0645\u0647 \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u0648 \u0634\u0631\u0627\u06cc\u0637 \u0627\u06cc\u0645\u0646 \u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u0631\u0627\u0646\u0646\u062f\u06af\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2>\u0646\u062a\u06cc\u062c\u0647 \u06af\u06cc\u0631\u06cc<\/h2>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u062a\u062d\u0644\u06cc\u0644 \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u067e\u0631\u062f\u0627\u062e\u062a\u06cc\u0645. \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u060c \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0627\u06cc\u0646 \u06a9\u0647 \u0647\u0648\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u062f\u0631 \u0622\u0646 \u0647\u0627 \u06af\u0631\u062f\u0634 \u067e\u06cc\u062f\u0627 \u0646\u0645\u06cc \u06a9\u0646\u062f\u060c \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062a\u0647\u0648\u06cc\u0647 \u0645\u0646\u0627\u0633\u0628\u06cc \u062f\u0627\u0631\u0646\u062f. \u0627\u06cc\u0646 \u062a\u0647\u0648\u06cc\u0647 \u0647\u0645 \u0628\u0631\u0627\u06cc \u062e\u0627\u0631\u062c \u06a9\u0631\u062f\u0646 \u0647\u0648\u0627\u06cc \u0622\u0644\u0648\u062f\u0647 \u0648 \u0648\u0627\u0631\u062f \u06a9\u0631\u062f\u0646 \u0647\u0648\u0627\u06cc \u062a\u0627\u0632\u0647 \u0648 \u067e\u0627\u06a9 \u06a9\u0627\u0631\u0628\u0631\u062f \u062f\u0627\u0631\u062f \u0648 \u0647\u0645 \u0627\u06cc\u0646 \u06a9\u0647 \u062f\u0631 \u0645\u0648\u0642\u0639 \u0622\u062a\u0634 \u0633\u0648\u0632\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u062b\u0645\u0631 \u062b\u0645\u0631 \u0648\u0627\u0642\u0639 \u0645\u06cc \u0634\u0648\u062f.\u200b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u0645 \u0628\u0647 \u0646\u0642\u062f \u0648 \u0628\u0631\u0631\u0633\u06cc \u062a\u0647\u0648\u06cc\u0647 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u0628\u067e\u0631\u062f\u0627\u0632\u06cc\u0645. \u0628\u0627\u06cc\u062f \u0627\u0630\u0639\u0627\u0646 \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0633\u06cc\u0633\u062a\u0645 &#8230; <a class=\"cz_readmore\" href=\"https:\/\/www.vent.ir\/fa\/%d8%aa%d9%87%d9%88%db%8c%d9%87-%d9%be%d8%a7%d8%b1%da%a9%db%8c%d9%86%da%af-%d9%87%d8%a7%db%8c-%d8%b2%db%8c%d8%b1-%d8%b2%d9%85%db%8c%d9%86%db%8c\/\"><i class=\"fas fa-angle-left\" aria-hidden=\"true\"><\/i><span>\u0627\u062f\u0627\u0645\u0647 \u0645\u0637\u0644\u0628<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextinma_seo_power":"","_daextinma_enable_ail":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-10152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-8"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/posts\/10152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/comments?post=10152"}],"version-history":[{"count":0,"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/posts\/10152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/media\/10154"}],"wp:attachment":[{"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/media?parent=10152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/categories?post=10152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vent.ir\/fa\/wp-json\/wp\/v2\/tags?post=10152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}